{"id":1828,"date":"2018-12-30T21:38:00","date_gmt":"2018-12-30T21:38:00","guid":{"rendered":"http:\/\/cenedcursos.com.br\/posgraduacao\/?post_type=product&#038;p=1828"},"modified":"2022-10-06T18:48:08","modified_gmt":"2022-10-06T18:48:08","slug":"artes-na-educacao-infantil","status":"publish","type":"product","link":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/","title":{"rendered":"Artes na Educa\u00e7\u00e3o Infantil"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><span style=\"font-size: 140%;\">P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A Educa\u00e7\u00e3o Art\u00edstica pode ter um grande impacto no desenvolvimento cognitivo, f\u00edsico, emocional e social positivo. Segundo a Associa\u00e7\u00e3o Nacional de Educa\u00e7\u00e3o Art\u00edstica, a arte pode ajudar as crian\u00e7as a desenvolver habilidades de pensamento cr\u00edtico, destreza e imagina\u00e7\u00e3o. Isso se traduz em habilidades do mundo real, como resolu\u00e7\u00e3o de problemas e planejamento estrat\u00e9gico. O ensino de arte pode promover o desenvolvimento emocional positivo, incentivando as crian\u00e7as a identificar e analisar seus sentimentos e, assim, desenvolver uma compreens\u00e3o mais profunda de si mesmas. A educa\u00e7\u00e3o formal visa ajudar a crian\u00e7a a crescer e se tornar um membro funcional da sociedade. As escolas conseguem isso atrav\u00e9s do ensino de disciplinas que incluem leitura, matem\u00e1tica, ci\u00eancias e hist\u00f3ria.<\/span><\/p>\n<h4 id=\"ui-id-3\" class=\"qodef-accordion-title ui-accordion-header ui-state-default ui-accordion-header-active ui-state-active ui-corner-top\" style=\"text-align: justify;\" tabindex=\"0\" role=\"tab\" aria-controls=\"ui-id-4\" aria-selected=\"true\" aria-expanded=\"true\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Objetivo<\/span><\/h4>\n<div id=\"ui-id-4\" class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" style=\"text-align: justify;\" role=\"tabpanel\" aria-labelledby=\"ui-id-3\" aria-hidden=\"false\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\"><span style=\"color: #000000;\">Fornecer, modelar e desenvolver pr\u00e1ticas de ensino exemplares, socialmente respons\u00e1veis e ecologicamente conscientes, dentro e atrav\u00e9s de contextos, com foco nas artes visuais da cultura e da sociedade.<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h4 id=\"ui-id-5\" class=\"qodef-accordion-title ui-accordion-header ui-state-default ui-corner-all ui-state-focus\" style=\"text-align: justify;\" tabindex=\"-1\" role=\"tab\" aria-controls=\"ui-id-6\" aria-selected=\"false\" aria-expanded=\"false\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">P\u00fablico Alvo<\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">O curso de p\u00f3s-gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil \u00e9 proposto aos portadores de diplomas das Ci\u00eancias da Educa\u00e7\u00e3o e afins, como Normal Superior, Pedagogia, Artes, Licenciaturas diversas, bem como aos profissionais atuantes na educa\u00e7\u00e3o, como professores, diretores, supervisores, coordenadores, entre outros. O curso \u00e9 aberto aos profissionais das demais \u00e1reas que desejam adquirir conhecimento interdisciplinar no objeto do curso.<\/span><\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">M\u00d3DULO<\/span><\/th>\n<th style=\"width: 88.3918%; text-align: justify;\"><span style=\"color: #000000;\">DISCIPLINA<\/span><\/th>\n<th style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">CH<\/span><\/th>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">1<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Doc\u00eancia no Ensino Superior<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">O Ensino Superior no Brasil. A Universidade na Sociedade. Legisla\u00e7\u00e3o da Educa\u00e7\u00e3o Superior. A Pr\u00e1tica Docente no Contexto da LDB (Lei n.\u00ba 9.394\/96). As Teorias Pedag\u00f3gicas. A Did\u00e1tica: Defini\u00e7\u00e3o e Import\u00e2ncia no Ensino Superior. Planejamento do Ensino. Elabora\u00e7\u00e3o de Planos de Ensino e Pr\u00e1tica Docente. Avalia\u00e7\u00e3o Educacional. Ambiente Virtual de Aprendizagem e Tecnologias para o Ensino. Intera\u00e7\u00f5es em Sala de Aula EAD e Presencial: O Papel dos Professores e dos Alunos.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">2<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Metodologia do Trabalho Cient\u00edfico<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Conceitos de Ci\u00eancia; M\u00e9todo Cient\u00edfico; Hip\u00f3teses; Vari\u00e1veis; Probabilidade; Validade; Fidedignidade; Amostragem; Delineamentos De Pesquisa; Metodologia Qualitativa e Quantitativa; Aplica\u00e7\u00e3o de Question\u00e1rio em Pesquisas; Caracteriza\u00e7\u00e3o da Linguagem Cient\u00edfica e do Sistema de Produ\u00e7\u00e3o Cient\u00edfico; Elabora\u00e7\u00e3o de Pesquisa Acad\u00eamico-Cient\u00edfica; \u00c9tica na Pesquisa; T\u00e9cnicas de Apresenta\u00e7\u00e3o. Resumo Cient\u00edfico; Artigo Cient\u00edfico; Ficha Catalogr\u00e1fica, Pr\u00e9 Projeto de Pesquisa, Resenha, Relat\u00f3rios de Pesquisa, Fichamento.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">3<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Empreendedorismo Pessoal<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">O emprego do futuro; Habilidades do profissional do futuro: Flexibilidade cognitiva, Negocia\u00e7\u00e3o, Orienta\u00e7\u00e3o para servir, Julgamento e tomada de decis\u00f5es, Autocontrole e Intelig\u00eancia emocional, Coordena\u00e7\u00e3o com os outros, Gest\u00e3o de pessoas, Criatividade e Vis\u00e3o inovadora, Pensamento Critico, Resolu\u00e7\u00e3o de problemas, Busca constante de conhecimento, Lideran\u00e7a pelo exemplo, Conex\u00f5es interpessoais, Determina\u00e7\u00e3o e Flexibilidade, Assumindo Riscos, Investimento de recursos; Proatividade; Planejamento estrat\u00e9gico; Gest\u00e3o do Tempo; Gest\u00e3o de Recursos Pessoais; Gest\u00e3o do conhecimento; Gest\u00e3o motivacional.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">4<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Meios Digitais e o Profissional do Futuro<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">O que \u00e9 transforma\u00e7\u00e3o digital?; Quais s\u00e3o as tend\u00eancias da transforma\u00e7\u00e3o digital?; Intelig\u00eancia Artificial: trabalha com a cria\u00e7\u00e3o de m\u00e1quinas inteligentes que executam fun\u00e7\u00f5es de maneira semelhante aos humanos; Realidade Virtual: cria uma situa\u00e7\u00e3o similar \u00e0 real usando artif\u00edcios digitais e tecnol\u00f3gicos; Business Intelligence: a utiliza\u00e7\u00e3o de informa\u00e7\u00f5es e dados para gerar intelig\u00eancia que pode ser aplicada na tomada de decis\u00e3o de um neg\u00f3cio; Automa\u00e7\u00e3o de Marketing: usa a tecnologia para diminuir o trabalho manual e garantir a assertividade das a\u00e7\u00f5es de marketing de uma empresa; Data Science: a ci\u00eancia que analisa os dados para possibilitar decis\u00f5es mais assertivas; Como a transforma\u00e7\u00e3o digital afeta sua carreira?; Como se preparar profissionalmente?; Estude muito; Pense no cliente; Conhe\u00e7a seus concorrentes; Analise seus dados; Crie propostas de valor; Tente inovar; Como a revolu\u00e7\u00e3o digital influencia na escolha da carreira?; Carreiras digitais: minha profiss\u00e3o vai morrer?<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">5<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Marketing Pessoal<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Marketing Inteligente. Portif\u00f3lios de produtos. Marketing pessoal profissional. Promo\u00e7\u00e3o pessoal, da imagem e comunica\u00e7\u00e3o. Personal Branding.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">6<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">\u00c9tica e Cidadania<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">\u00c9tica e Moral: Conceitos e Evolu\u00e7\u00e3o Hist\u00f3rica; O que \u00e9 \u00c9tica e Moral?; Evolu\u00e7\u00e3o Hist\u00f3rica dos Conceitos; A Rela\u00e7\u00e3o entre \u00c9tica e Moral; \u00c9tica e Moral nas Rela\u00e7\u00f5es Sociais; \u00c9tica, Moral e ; Desafios do Exerc\u00edcio da Cidadania no Brasil; A Consolida\u00e7\u00e3o da Democracia ap\u00f3s 1988; Os Desafios para o Exerc\u00edcio Pleno da Cidadania; Direito; \u00c9tica na Pol\u00edtica; \u00c9tica das Convic\u00e7\u00f5es e \u00c9tica da Responsabilidade; \u00c9tica, Moral e Pol\u00edtica: A Constru\u00e7\u00e3o da Cidadania; O Conceito de Cidadania e sua Evolu\u00e7\u00e3o Hist\u00f3rica; Cidadania e Direitos Fundamentais; A Cidadania no Mundo Globalizado; Cidadania no Brasil; A Afirma\u00e7\u00e3o da Ideia de Cidadania no Brasil; A Cidadania no Imp\u00e9rio; A Cidadania na Rep\u00fablica; A Cidadania na Redemocratiza\u00e7\u00e3o; A Cidadania e as Desigualdades Sociais; \u00c9tica nas Rela\u00e7\u00f5es de Trabalho: O C\u00f3digo de \u00c9tica Profissional; \u00c9tica, Mercado e Institui\u00e7\u00f5es; A Responsabilidade Social das Organiza\u00e7\u00f5es; \u00c9tica nas Burocracias P\u00fablicas e Privadas; O C\u00f3digo de \u00c9tica Profissional; Os Conselhos Profissionais de \u00c9tica; \u00c9tica e Cidadania nas Rela\u00e7\u00f5es de Trabalho.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">7<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Hist\u00f3ria da Arte: da Pr\u00e9-Hist\u00f3ria ao Surrealismo<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Panorama Hist\u00f3rico, Art\u00edstico E Cultural Ao Longo Dos Tempos; A Revolu\u00e7\u00e3o Francesa E Suas Contribui\u00e7\u00f5es Para Uma Nova Vis\u00e3o De Sociedade, Homem E Arte; A Revolu\u00e7\u00e3o Industrial E A Arte Com Foco No Romantismo; A Realidade E As Concep\u00e7\u00f5es Art\u00edsticas Realistas E Naturalistas; As Vanguardas E A Explos\u00e3o Da Arte Moderna.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">8<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Est\u00e9tica Art\u00edstica<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Estudo Dos Fundamentos Da Est\u00e9tica E Da Filosofia Da Arte; Introdu\u00e7\u00e3o \u00c0 Reflex\u00e3o Est\u00e9tica, Po\u00e9tica E Cr\u00edtica Sobre A Obra De Arte; Discuss\u00e3o Sobre O Conceito De Belo, Prazer Est\u00e9tico; Fun\u00e7\u00e3o Social Da Arte E Quest\u00f5es Relacionadas \u00c0 Produ\u00e7\u00e3o, Recep\u00e7\u00e3o E Circula\u00e7\u00e3o Da Obra De Arte Em Diferentes Contextos Hist\u00f3rico-Culturais.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">9<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Estudo dos Elementos Representativos do Desenho<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Figura Humana: Construindo Arte E Ideias; O Desenho: Instrumento De Representa\u00e7\u00e3o, Compreens\u00e3o, Esbo\u00e7o E Estudo Das Formas Lineares E Pict\u00f3ricas Das Imagens Como Signo; O Desenho Como Parte De Um Sistema De Significa\u00e7\u00e3o; Breve Panorama Do Desenho Na Arte Ocidental.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">10<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Metodologia do Ensino de Arte-Educa\u00e7\u00e3o<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Did\u00e1tica; Abordagens Te\u00f3ricas E Conceituais Sobre Arte E Artistas; Planejamento Escolar; O Ensino Da Arte Dentro E Fora Do Ambiente Escolar; Forma\u00e7\u00e3o De Professores: Identidade E Contextos De Trabalho.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">11<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">O Interacionismo: Considera\u00e7\u00f5es sobre o Desenvolvimento Infantil; Uma Mudan\u00e7a Necess\u00e1ria: A Educa\u00e7\u00e3o Infantil Frente ao Ensino Fundamental de 09 Anos; As Classes de Alfabetiza\u00e7\u00e3o sob uma Perspectiva Construtivista S\u00f3cio-Interacionista; O Conhecimento Matem\u00e1tico, Hist\u00f3rico, Geografico, Art\u00edstico e o Letramento; Geografia, Hist\u00f3ria e Ci\u00eancias nas Classes de Alfabetiza\u00e7\u00e3o; As Artes e a Alfabetiza\u00e7\u00e3o; O Professor Alfabetizador.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\">12<\/span><\/th>\n<td style=\"width: 88.3918%; text-align: justify;\">\n<div class=\"qodef-accordion-holder qodef-ac-default  qodef-toggle clearfix accordion ui-accordion ui-accordion-icons ui-widget ui-helper-reset\">\n<h4 class=\"qodef-accordion-title ui-accordion-header ui-corner-top ui-accordion-header-active ui-state-active ui-state-hover\"><span class=\"qodef-tab-title\" style=\"color: #000000;\">Estrat\u00e9gias de Ensino Pelo L\u00fadico<\/span><\/h4>\n<div class=\"qodef-accordion-content ui-accordion-content ui-helper-reset ui-widget-content ui-corner-bottom ui-accordion-content-active\" role=\"tabpanel\" aria-hidden=\"true\">\n<div class=\"qodef-accordion-content-inner\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p><span style=\"color: #000000;\">Espa\u00e7os e Atividades Ludopedag\u00f3gicos; O \u00a0Jogo \u00a0como \u00a0Eixo \u00a0Estruturante \u00a0do \u00a0Curr\u00edculo \u00a0na Educa\u00e7\u00e3o Infantil; T\u00e9cnicas L\u00fadicas, Pedag\u00f3gicas e de Sensibiliza\u00e7\u00e3o: O Agora e o Desafio para o Futuro; Crit\u00e9rios \u00a0 para \u00a0 Sele\u00e7\u00e3o \u00a0 de \u00a0 Brinquedos, \u00a0 Jogos \u00a0 e Materiais.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<td style=\"width: 3.38573%; text-align: justify;\"><span style=\"color: #000000;\">60h<\/span><\/td>\n<\/tr>\n<tr>\n<th style=\"width: 8.10157%; text-align: justify;\"><span style=\"color: #000000;\"><strong>TOTAL<\/strong><\/span><\/th>\n<td style=\"width: 91.7775%; text-align: justify;\" colspan=\"2\"><span style=\"color: #000000;\"><strong>720h<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<h2><\/h2>\n<a data-animate=\"blurIn\" href=\"http:\/\/cenedcursos.com.br\/posgraduacao\/?add-to-cart=1833\" target=\"_self\" class=\"button primary is-larger box-shadow-4 expand\"  >\n    <span>Fa\u00e7a Aqui sua Matr\u00edcula<\/span>\n  <i class=\"icon-shopping-bag\" ><\/i><\/a>\n\n","protected":false},"featured_media":1823,"template":"","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"product_brand":[],"product_cat":[98],"product_tag":[244,245],"class_list":{"0":"post-1828","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-educacao","7":"product_tag-artes","8":"product_tag-educacao-infantil","10":"first","11":"instock","12":"sale","13":"featured","14":"shipping-taxable","15":"product-type-simple"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC<\/title>\n<meta name=\"description\" content=\"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC\" \/>\n<meta property=\"og:description\" content=\"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00f3s-Gradua\u00e7\u00e3o \u00e0 Dist\u00e2ncia...Reconhecidos pelo MEC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T18:48:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC\" \/>\n<meta name=\"twitter:description\" content=\"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/\",\"url\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/\",\"name\":\"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC\",\"isPartOf\":{\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg\",\"datePublished\":\"2018-12-30T21:38:00+00:00\",\"dateModified\":\"2022-10-06T18:48:08+00:00\",\"description\":\"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil\",\"breadcrumb\":{\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage\",\"url\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg\",\"contentUrl\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg\",\"width\":1280,\"height\":948,\"caption\":\"artes na educa\u00e7\u00e3o infantil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cursos\",\"item\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/todos-os-cursos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Artes na Educa\u00e7\u00e3o Infantil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/#website\",\"url\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/\",\"name\":\"P\u00f3s-Gradua\u00e7\u00e3o \u00e0 Dist\u00e2ncia...Reconhecidos pelo MEC\",\"description\":\"Diversos Cursos de P\u00f3s-Gradua\u00e7\u00e3o a Dist\u00e2ncia Reconhecidos pelo MEC e certificados pela Universidade C\u00e2ndido Mendes (UCAM)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cenedcursos.com.br\/posgraduacao\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC","description":"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/","og_locale":"pt_BR","og_type":"article","og_title":"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC","og_description":"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil","og_url":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/","og_site_name":"P\u00f3s-Gradua\u00e7\u00e3o \u00e0 Dist\u00e2ncia...Reconhecidos pelo MEC","article_modified_time":"2022-10-06T18:48:08+00:00","og_image":[{"width":1280,"height":948,"url":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC","twitter_description":"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil","twitter_image":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/","url":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/","name":"Artes na Educa\u00e7\u00e3o Infantil - P\u00f3s-Gradua\u00e7\u00e3o Reconhecida pelo MEC","isPartOf":{"@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage"},"image":{"@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg","datePublished":"2018-12-30T21:38:00+00:00","dateModified":"2022-10-06T18:48:08+00:00","description":"O curso de P\u00f3s-Gradua\u00e7\u00e3o em Artes na Educa\u00e7\u00e3o Infantil aborda Est\u00e9tica Art\u00edstica, Estudo dos Elementos do Desenho, Teorias e Pr\u00e1ticas da Educa\u00e7\u00e3o Infantil","breadcrumb":{"@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#primaryimage","url":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg","contentUrl":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-content\/uploads\/2018\/12\/artes-na-educa\u00e7\u00e3o-infantil.jpg","width":1280,"height":948,"caption":"artes na educa\u00e7\u00e3o infantil"},{"@type":"BreadcrumbList","@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/produto\/artes-na-educacao-infantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cenedcursos.com.br\/posgraduacao\/"},{"@type":"ListItem","position":2,"name":"Cursos","item":"https:\/\/cenedcursos.com.br\/posgraduacao\/todos-os-cursos\/"},{"@type":"ListItem","position":3,"name":"Artes na Educa\u00e7\u00e3o Infantil"}]},{"@type":"WebSite","@id":"https:\/\/cenedcursos.com.br\/posgraduacao\/#website","url":"https:\/\/cenedcursos.com.br\/posgraduacao\/","name":"P\u00f3s-Gradua\u00e7\u00e3o \u00e0 Dist\u00e2ncia...Reconhecidos pelo MEC","description":"Diversos Cursos de P\u00f3s-Gradua\u00e7\u00e3o a Dist\u00e2ncia Reconhecidos pelo MEC e certificados pela Universidade C\u00e2ndido Mendes (UCAM)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cenedcursos.com.br\/posgraduacao\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/product\/1828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/media\/1823"}],"wp:attachment":[{"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/product_brand?post=1828"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/product_cat?post=1828"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cenedcursos.com.br\/posgraduacao\/wp-json\/wp\/v2\/product_tag?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}